{"id":46948,"date":"1970-01-01T09:00:00","date_gmt":"1970-01-01T00:00:00","guid":{"rendered":"https:\/\/stg2.kawajun.biz\/en\/hardware\/products\/item1291\/"},"modified":"2025-09-29T15:43:43","modified_gmt":"2025-09-29T06:43:43","slug":"item1291","status":"publish","type":"products","link":"https:\/\/kawajun.biz\/en\/hardware\/products\/item1291\/","title":{"rendered":"Lever Handle with Rose only (JKC-DJ4)"},"content":{"rendered":"","protected":false},"featured_media":0,"template":"","meta":{"_acf_changed":false},"products_category":[11],"class_list":["post-46948","products","type-products","status-publish","hentry","products_category-leverhandle"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/kawajun.biz\/en\/hardware\/wp-json\/wp\/v2\/products\/46948","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/kawajun.biz\/en\/hardware\/wp-json\/wp\/v2\/products"}],"about":[{"href":"https:\/\/kawajun.biz\/en\/hardware\/wp-json\/wp\/v2\/types\/products"}],"wp:attachment":[{"href":"https:\/\/kawajun.biz\/en\/hardware\/wp-json\/wp\/v2\/media?parent=46948"}],"wp:term":[{"taxonomy":"products_category","embeddable":true,"href":"https:\/\/kawajun.biz\/en\/hardware\/wp-json\/wp\/v2\/products_category?post=46948"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}