{"id":47184,"date":"1970-01-01T09:00:00","date_gmt":"1970-01-01T00:00:00","guid":{"rendered":"https:\/\/stg2.kawajun.biz\/en\/hardware\/products\/item1527\/"},"modified":"2025-09-29T15:44:33","modified_gmt":"2025-09-29T06:44:33","slug":"item1527","status":"publish","type":"products","link":"https:\/\/kawajun.biz\/en\/hardware\/products\/item1527\/","title":{"rendered":"Lever Handle with Rose only (TWC-K)"},"content":{"rendered":"","protected":false},"featured_media":0,"template":"","meta":{"_acf_changed":false},"products_category":[11],"class_list":["post-47184","products","type-products","status-publish","hentry","products_category-leverhandle"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/kawajun.biz\/en\/hardware\/wp-json\/wp\/v2\/products\/47184","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/kawajun.biz\/en\/hardware\/wp-json\/wp\/v2\/products"}],"about":[{"href":"https:\/\/kawajun.biz\/en\/hardware\/wp-json\/wp\/v2\/types\/products"}],"wp:attachment":[{"href":"https:\/\/kawajun.biz\/en\/hardware\/wp-json\/wp\/v2\/media?parent=47184"}],"wp:term":[{"taxonomy":"products_category","embeddable":true,"href":"https:\/\/kawajun.biz\/en\/hardware\/wp-json\/wp\/v2\/products_category?post=47184"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}