{"id":48517,"date":"1970-01-01T09:00:00","date_gmt":"1970-01-01T00:00:00","guid":{"rendered":"https:\/\/stg2.kawajun.biz\/en\/hardware\/products\/item2860\/"},"modified":"2025-09-29T15:55:21","modified_gmt":"2025-09-29T06:55:21","slug":"item2860","status":"publish","type":"products","link":"https:\/\/kawajun.biz\/en\/hardware\/products\/item2860\/","title":{"rendered":"Pull &#038; Knob (PC-397-XC)"},"content":{"rendered":"","protected":false},"featured_media":0,"template":"","meta":{"_acf_changed":false},"products_category":[4],"class_list":["post-48517","products","type-products","status-publish","hentry","products_category-funitureknob"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/kawajun.biz\/en\/hardware\/wp-json\/wp\/v2\/products\/48517","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/kawajun.biz\/en\/hardware\/wp-json\/wp\/v2\/products"}],"about":[{"href":"https:\/\/kawajun.biz\/en\/hardware\/wp-json\/wp\/v2\/types\/products"}],"wp:attachment":[{"href":"https:\/\/kawajun.biz\/en\/hardware\/wp-json\/wp\/v2\/media?parent=48517"}],"wp:term":[{"taxonomy":"products_category","embeddable":true,"href":"https:\/\/kawajun.biz\/en\/hardware\/wp-json\/wp\/v2\/products_category?post=48517"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}